{"id":31926,"date":"2026-02-18T01:41:02","date_gmt":"2026-02-18T01:41:02","guid":{"rendered":"https:\/\/www.alesportperu.com\/producto\/set-lady-2\/"},"modified":"2026-08-28T16:59:01","modified_gmt":"2026-08-28T16:59:01","slug":"set-lady-2","status":"publish","type":"product","link":"https:\/\/www.alesportperu.com\/es_es\/producto\/set-lady-2\/","title":{"rendered":"Zapatilla Joma Set Lady"},"content":{"rendered":"<p>Zapatillas de tenis para hombre. Perfectas para jugadores en fase de perfeccionamiento, estas zapatillas ofrecen una pisada c\u00f3moda, excelente sujeci\u00f3n lateral y estabilidad gracias a los sistemas t\u00e9cnicos que lleva incorporada.<\/p>\n<p>Upper elaborado con mesh t\u00e9cnico, un material ligero y transpirable. El sistema VTS permite un flujo de aire constante, manteniendo los pies frescos y secos incluso en las sesiones m\u00e1s intensas. El sistema termosellado JOMA SPORTECH proporciona un ajuste c\u00f3modo sin a\u00f1adir peso a las zapatillas.<\/p>\n<p>En las zonas m\u00e1s expuestas a la abrasi\u00f3n y a la fricci\u00f3n, se han integrado refuerzos PROTECTION.<\/p>\n<p>Mediasuela de phylon ligero, flexible y con capacidad para absorber los impactos. El sistema STABILIS, ubicado en la zona del puente y del tal\u00f3n, proporciona un soporte adicional en cada movimiento. Al distribuir de manera uniforme la presi\u00f3n, evita sobrecarga o movimientos inestables.<\/p>\n<p>Suela de caucho DURABILITY all court, apta y resistente para jugar en pista dura\/r\u00e1pida. Su estructura permite un control \u00f3ptimo de los deslizamientos seg\u00fan se necesite.<\/p>","protected":false},"excerpt":{"rendered":"<h2>Caracter\u00edsticas<\/h2>\n<ul class=\"features list\">\n<li>Corte con mesh transpirable VTS<\/li>\n<li>Corte con sistema de ajuste termosellado SPORTECH<\/li>\n<li>Mediasuela de phylon con STABILIS<\/li>\n<li>Suela de caucho DURABILITY<\/li>\n<li>Refuerzo PROTECTION<\/li>\n<\/ul>","protected":false},"featured_media":31922,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[76],"product_tag":[],"class_list":["post-31926","product","type-product","status-publish","has-post-thumbnail","product_cat-mujer","first","instock","sale","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product\/31926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/comments?post=31926"}],"version-history":[{"count":3,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product\/31926\/revisions"}],"predecessor-version":[{"id":36908,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product\/31926\/revisions\/36908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/media\/31922"}],"wp:attachment":[{"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/media?parent=31926"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product_brand?post=31926"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product_cat?post=31926"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.alesportperu.com\/es_es\/wp-json\/wp\/v2\/product_tag?post=31926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}